{"id":111,"count":5,"description":"Bienvenidos a la moderna f\u00e1brica de acero inoxidable de Dongzhaowei. Desde la producci\u00f3n hasta el embalaje y el env\u00edo, cada paso refleja nuestro firme compromiso con la calidad y la eficiencia. Gracias a nuestra maquinaria avanzada, nuestras l\u00edneas de producci\u00f3n automatizadas y nuestro personal cualificado, nos aseguramos de que cada pieza de equipamiento para buf\u00e9 cumpla con las normas internacionales y mantenga una calidad superior en todo momento.","link":"https:\/\/www.dzwchafingdish.com\/es\/video-category\/factory-and-production\/","name":"F\u00e1brica y producci\u00f3n","slug":"factory-and-production","taxonomy":"video-category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dzwchafingdish.com\/es\/wp-json\/wp\/v2\/video-category\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dzwchafingdish.com\/es\/wp-json\/wp\/v2\/video-category"}],"about":[{"href":"https:\/\/www.dzwchafingdish.com\/es\/wp-json\/wp\/v2\/taxonomies\/video-category"}],"wp:post_type":[{"href":"https:\/\/www.dzwchafingdish.com\/es\/wp-json\/wp\/v2\/video?video-category=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}